{"id":1798,"date":"2026-05-11T08:49:42","date_gmt":"2026-05-11T07:49:42","guid":{"rendered":"https:\/\/zaccararoberto.eu\/index.php\/newsletter\/"},"modified":"2026-05-13T16:20:48","modified_gmt":"2026-05-13T15:20:48","slug":"newsletter","status":"publish","type":"page","link":"https:\/\/zaccararoberto.eu\/index.php\/newsletter\/","title":{"rendered":"Newsletter"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"212\" src=\"https:\/\/zaccararoberto.eu\/wp-content\/uploads\/2026\/05\/Newsletter-1-300x212.jpg\" alt=\"newsletter-foto\" class=\"wp-image-1932 size-medium\" srcset=\"https:\/\/zaccararoberto.eu\/wp-content\/uploads\/2026\/05\/Newsletter-1-300x212.jpg 300w, https:\/\/zaccararoberto.eu\/wp-content\/uploads\/2026\/05\/Newsletter-1.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Non ci sono novit\u00e0 di particolare importanza per i lettori.<\/p>\n<\/div><\/div>\n\n\n\n<p><a href=\"https:\/\/www.msn.com\/it-it\/notizie\/milano\/hantavirus-individuato-un-contatto-a-milano-%C3%A8-un-turista-britannico-che-ha-volato-con-la-moglie-della-prima-vittima\/ar-AA232aJ2?ocid=msedgntp&amp;pc=U531&amp;cvid=6a044b5a6e974b34bf10379b4025179b&amp;ei=17\">Hantavirus, individuato un contatto a Milano: \u00e8 un turista britannico che ha volato con la moglie della prima vittima<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non ci sono novit\u00e0 di particolare importanza per i lettori. Hantavirus, individuato un contatto a Milano: \u00e8 un turista britannico che ha volato con la moglie della prima vittima<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-1798","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/zaccararoberto.eu\/index.php\/wp-json\/wp\/v2\/pages\/1798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zaccararoberto.eu\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zaccararoberto.eu\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zaccararoberto.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zaccararoberto.eu\/index.php\/wp-json\/wp\/v2\/comments?post=1798"}],"version-history":[{"count":4,"href":"https:\/\/zaccararoberto.eu\/index.php\/wp-json\/wp\/v2\/pages\/1798\/revisions"}],"predecessor-version":[{"id":1977,"href":"https:\/\/zaccararoberto.eu\/index.php\/wp-json\/wp\/v2\/pages\/1798\/revisions\/1977"}],"wp:attachment":[{"href":"https:\/\/zaccararoberto.eu\/index.php\/wp-json\/wp\/v2\/media?parent=1798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}